{"id":801,"date":"2015-12-21T20:24:29","date_gmt":"2015-12-21T18:24:29","guid":{"rendered":"http:\/\/www.mvenzenkirchen.at\/cms\/?p=801"},"modified":"2015-12-21T20:25:17","modified_gmt":"2015-12-21T18:25:17","slug":"mve-revue-2015","status":"publish","type":"post","link":"http:\/\/www.mvenzenkirchen.at\/cms\/mve-revue-2015\/","title":{"rendered":"MVE revue 2015"},"content":{"rendered":"<p>F\u00fcr alle, denen wir keine musikalischen Weihnachtsgr\u00fc\u00dfe \u00fcberbringen konnten &#8211; hier der Jahresr\u00fcckblick des Musikvereins Enzenkirchen in Form der &#8222;MVE revue 2015&#8220;.<\/p>\n<p>Wir w\u00fcnschen unseren Freunden und Unterst\u00fctzern besinnliche Weihnachtsfeiertage und einen guten Rutsch ins Jahr 2016.<\/p>\n<p>&nbsp;<\/p>\n<p><iframe width=\"525\" height=\"371\" src=\"\/\/e.issuu.com\/embed.html#6758281\/32121881\" frameborder=\"0\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>F\u00fcr alle, denen wir keine musikalischen Weihnachtsgr\u00fc\u00dfe \u00fcberbringen konnten &#8211; hier der Jahresr\u00fcckblick [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-801","post","type-post","status-publish","format-standard","hentry","category-akutelles"],"_links":{"self":[{"href":"http:\/\/www.mvenzenkirchen.at\/cms\/wp-json\/wp\/v2\/posts\/801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.mvenzenkirchen.at\/cms\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.mvenzenkirchen.at\/cms\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.mvenzenkirchen.at\/cms\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.mvenzenkirchen.at\/cms\/wp-json\/wp\/v2\/comments?post=801"}],"version-history":[{"count":3,"href":"http:\/\/www.mvenzenkirchen.at\/cms\/wp-json\/wp\/v2\/posts\/801\/revisions"}],"predecessor-version":[{"id":804,"href":"http:\/\/www.mvenzenkirchen.at\/cms\/wp-json\/wp\/v2\/posts\/801\/revisions\/804"}],"wp:attachment":[{"href":"http:\/\/www.mvenzenkirchen.at\/cms\/wp-json\/wp\/v2\/media?parent=801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.mvenzenkirchen.at\/cms\/wp-json\/wp\/v2\/categories?post=801"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.mvenzenkirchen.at\/cms\/wp-json\/wp\/v2\/tags?post=801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}